{"id":1230,"date":"2023-04-12T14:36:21","date_gmt":"2023-04-12T14:36:21","guid":{"rendered":"http:\/\/www.puertosbolivia.com\/?p=1230"},"modified":"2025-12-05T18:22:15","modified_gmt":"2025-12-05T18:22:15","slug":"el-diario-119-anos-ligado-a-la-historia-de-bolivia","status":"publish","type":"post","link":"https:\/\/www.puertosbolivia.com\/index.php\/el-diario-119-anos-ligado-a-la-historia-de-bolivia\/","title":{"rendered":"EL DIARIO, 119 a\u00f1os ligado a la historia de Bolivia"},"content":{"rendered":"<p>Por Clovis D\u00edaz de Oropeza F.<\/p>\n<p>Al finalizar el Siglo XIX y comienzo del Siglo XX, nuestra patria cargaba las consecuencias de la enajenaci\u00f3n de su litoral por Chile y la p\u00e9rdida del Acre, desde entonces en poder de Brasil. Pese a que gozaba de excelente econom\u00eda por el alto precio de la plata, Bolivia llevaba clavadas en el coraz\u00f3n esas dos siniestras heridas.<br \/>\nEn aquel contradictorio escenario de p\u00e9rdidas territoriales y de mejor\u00eda econ\u00f3mica eventual por la venta internacional de plata, naci\u00f3 EL DIARIO, fundado el 5 de abril de 1904, por Jos\u00e9 Carrasco Torrico, en La Paz, sede de gobierno y la ciudad m\u00e1s concurrida de Bolivia.<br \/>\nImaginamos aquel espacio hist\u00f3rico, estampado por reyertas entre liberales y republicanos, que se turnaban en el manejo del gobierno de Bolivia, \u00e9poca de las primeras v\u00edas f\u00e9rreas por las que transitaba el ferrocarril uniendo a moros y cristianos en las estaciones repletas de personas esperando a familiares y tambi\u00e9n colmadas de viajeros con su equipaje, listos para abordar las potentes locomotoras. A\u00f1os en que viajar en el tren fue s\u00edmbolo de cierto estatus.<br \/>\nImaginamos a Jos\u00e9 Carrasco, trabajando en el primer n\u00famero de EL DIARIO, en alguna imprenta de la \u00e9poca, con los linotipistas tecleando las notas y acompa\u00f1ados por el ruido que hac\u00edan al manejar con destreza y gran velocidad, los diferentes \u201ctipos\u201d de letras que, una por una, iban formando palabras, oraciones y, en suma, el texto a publicarse.<br \/>\nImaginamos la salida de EL DIARIO a las calles de La Paz, con los primeros voceadores, llamados \u201ccanillitas\u201d porque usaban las \u201ccanillas\u201d para correr y vender las ediciones impresas del matutino.<br \/>\nVeloces tibias que dieron vida al primer Sindicato de canillitas reunido desde el amanecer en lo que hoy conocemos como la \u201cCasa de EL DIARIO\u201d en la Calle Loayza de nuestra \u00ednclita Ciudad de La Paz.<br \/>\nSin importar el fr\u00edo o la lluvia, los voceadores gritaban a pulm\u00f3n abierto \u00a1EL DIARIO\u00a1, venta matinal que, para ellos y sus familias, significaba ganar el pan de cada d\u00eda.<br \/>\nEl matutino se agigant\u00f3 en cada edici\u00f3n y fue creciendo a nivel nacional porque siempre abri\u00f3 sus p\u00e1ginas a la intelectualidad boliviana, sin mirar posiciones ideol\u00f3gicas ni pol\u00edticas.<br \/>\nSi hici\u00e9ramos un recuento minucioso de p\u00e1ginas y suplementos encontrar\u00edamos notas de un c\u00e9lebre Franz Tamayo, de una gran poetisa como Alcira Cardona y, por supuesto, de conocidos pol\u00edticos que, en 119 a\u00f1os, publicaron su pensamiento y su enfoque personal en todos los temas habidos y por haber.<br \/>\nEn cuanto a ilustradores y caricaturistas, EL DIARIO es un emporio que nos muestra las firmas de Don Jos\u00e9, Rod Bal y el gran dibujante y actual autor de \u201cAfiches\u201d, Lusbel.<br \/>\nEl material fotogr\u00e1fico, por su gran variedad y \u00f3ptima calidad, podr\u00eda relatarnos momentos especiales con personajes especiales.<br \/>\nLas publicaciones de EL DIARIO, almacenan 119 a\u00f1os de Cultura, Historia y pol\u00edtica de nuestro pa\u00eds y no hay un referente nacional que posea tanto material que, por supuesto, es hist\u00f3rico.<br \/>\nDe la fundaci\u00f3n del destacado matutino por Jos\u00e9 Carrasco, a la actual directiva integrada por Jorge y Antonio Carrasco, se repite la invariable vocaci\u00f3n de defender la causa nacional que es Bolivia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Clovis D\u00edaz de Oropeza F. Al finalizar el Siglo XIX y comienzo del Siglo XX, nuestra patria cargaba las consecuencias de la enajenaci\u00f3n de su litoral por Chile y la p\u00e9rdida del Acre, desde entonces en poder de Brasil. Pese a que gozaba de <span class=\"more-button\"><a class=\"more-link\" href=\"https:\/\/www.puertosbolivia.com\/index.php\/el-diario-119-anos-ligado-a-la-historia-de-bolivia\/\">Ver mas<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[6],"_links":{"self":[{"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/posts\/1230"}],"collection":[{"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/comments?post=1230"}],"version-history":[{"count":1,"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/posts\/1230\/revisions"}],"predecessor-version":[{"id":1231,"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/posts\/1230\/revisions\/1231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/media\/429"}],"wp:attachment":[{"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/media?parent=1230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/categories?post=1230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.puertosbolivia.com\/index.php\/wp-json\/wp\/v2\/tags?post=1230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}